{"id":3750,"date":"2021-09-17T11:25:12","date_gmt":"2021-09-17T09:25:12","guid":{"rendered":"https:\/\/www.steinhoff.eu\/?page_id=3750"},"modified":"2022-07-12T13:35:43","modified_gmt":"2022-07-12T11:35:43","slug":"straightening_transport_rolls","status":"publish","type":"page","link":"https:\/\/www.steinhoff.eu\/en\/straightening_transport_rolls\/","title":{"rendered":"Straightening &#038; Transport Rolls"},"content":{"rendered":"<p>[vc_row tm_bgimagefixed=&#8221;&#8221; css=&#8221;.vc_custom_1623671572496{padding-top: 88px !important;padding-bottom: 0px !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;2513&#8243; img_size=&#8221;full&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_custom_heading text=&#8221;Straightening &amp; Transport Rolls&#8221; font_container=&#8221;tag:h1|font_size:48px|text_align:left|color:%23014480|line_height:56px&#8221; google_fonts=&#8221;font_family:Poppins%3A100%2C100italic%2C200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C500%2C500italic%2C600%2C600italic%2C700%2C700italic%2C800%2C800italic%2C900%2C900italic|font_style:300%20light%20regular%3A300%3Anormal&#8221;]<ul class=\"tm-list tm-list-style-icon tm-list-icon-color-skincolor tm- tm-icon-skincolor tm-list-textsize- tm-list-icon-library-fontawesome\"><li><i class=\"tm-skincolor fa fa-caret-right\"><\/i>  <span class=\"tm-list-li-content\">Rolls for hot \/ cold straightening\n<\/span><\/li><li><i class=\"tm-skincolor fa fa-caret-right\"><\/i>  <span class=\"tm-list-li-content\">Heat treatment:\n<br>\u2022 Uniform barrel hardness\n<br>\u2022 Hardening depths up to a barrel radius  of 50 millimetres\n<br>\u2022 Excellent wear resistance\n<br>\u2022 Optimised residual stress levels<\/span><\/li><li><i class=\"tm-skincolor fa fa-caret-right\"><\/i>  <span class=\"tm-list-li-content\">Mechanical production:\n<br>\u2022 Greatest dimensional accuracy\n<br>\u2022 Greatest concentricity\n<br>\u2022 Required hardness specification through specific selection of materials and additional heat treatments<\/span><\/li><\/ul>[\/vc_column][\/vc_row][vc_row][vc_column][vc_custom_heading text=&#8221;YOUR INQUIRY&#8221; font_container=&#8221;tag:h1|font_size:48px|text_align:left|color:%23014480|line_height:56px&#8221; google_fonts=&#8221;font_family:Poppins%3A100%2C100italic%2C200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C500%2C500italic%2C600%2C600italic%2C700%2C700italic%2C800%2C800italic%2C900%2C900italic|font_style:300%20light%20regular%3A300%3Anormal&#8221;]<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-3723\"><form id=\"wpforms-form-3723\" class=\"wpforms-validate wpforms-form\" data-formid=\"3723\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/3750?wpforms_form_id=3723\" data-token=\"12ab61f7f7852d878e5a44ee556ee758\" data-token-time=\"1778708046\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-3723-field_2-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-3723-field_2\">Company Name<\/label><input type=\"text\" id=\"wpforms-3723-field_2\" class=\"wpforms-field-large\" name=\"wpforms[fields][2]\" ><\/div><div id=\"wpforms-3723-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-3723-field_1\">Contact Person <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-3723-field_1\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][1][first]\" placeholder=\"Name\" required><label for=\"wpforms-3723-field_1\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-3723-field_1-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][1][last]\" placeholder=\"Surname\" required><label for=\"wpforms-3723-field_1-last\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">Last<\/label><\/div><\/div><\/div><div id=\"wpforms-3723-field_8-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-3723-field_8\">Contact Details <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-3723-field_8\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][8][first]\" placeholder=\"Phone\" required><label for=\"wpforms-3723-field_8\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-3723-field_8-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][8][last]\" placeholder=\"E-Mail Address\" required><label for=\"wpforms-3723-field_8-last\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">Last<\/label><\/div><\/div><\/div><div id=\"wpforms-3723-field_3-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-modern\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-3723-field_3\">Application Field<\/label><select id=\"wpforms-3723-field_3\" class=\"wpforms-field-large choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-large\" data-search-enabled=\"\" name=\"wpforms[fields][3]\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'><\/option><option value=\"Steel\"  class=\"choice-1 depth-1\"  >Steel<\/option><option value=\"Aluminium\"  class=\"choice-2 depth-1\"  >Aluminium<\/option><option value=\"Copper\"  class=\"choice-3 depth-1\"  >Copper<\/option><option value=\"Wood \/ Cellulose\"  class=\"choice-5 depth-1\"  >Wood \/ Cellulose<\/option><option value=\"Battery\"  class=\"choice-6 depth-1\"  >Battery<\/option><option value=\"Service \/ Support\"  class=\"choice-9 depth-1\"  >Service \/ Support<\/option><\/select><\/div><div id=\"wpforms-3723-field_5-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-modern\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-3723-field_5\">Choose Roll<\/label><select id=\"wpforms-3723-field_5\" class=\"wpforms-field-large choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-large\" data-search-enabled=\"\" name=\"wpforms[fields][5]\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'><\/option><option value=\"Work Rolls\"  class=\"choice-1 depth-1\"  >Work Rolls<\/option><option value=\"Stamping Rolls\"  class=\"choice-2 depth-1\"  >Stamping Rolls<\/option><option value=\"Straightening &amp; Transport Rolls\"  class=\"choice-3 depth-1\"  >Straightening &amp; Transport Rolls<\/option><option value=\"Back-Up Rolls\"  class=\"choice-4 depth-1\"  >Back-Up Rolls<\/option><option value=\"Intermediate Rolls\"  class=\"choice-5 depth-1\"  >Intermediate Rolls<\/option><option value=\"Calander Rolls\"  class=\"choice-7 depth-1\"  >Calander Rolls<\/option><option value=\"Roll Equipment\"  class=\"choice-6 depth-1\"  >Roll Equipment<\/option><\/select><\/div><div id=\"wpforms-3723-field_11-container\" class=\"wpforms-field wpforms-field-file-upload\" data-field-id=\"11\"><label class=\"wpforms-field-label\" for=\"wpforms-3723-field_11\">Upload<\/label><div\n\t\tclass=\"wpforms-uploader \"\n\t\tdata-field-id=\"11\"\n\t\tdata-form-id=\"3723\"\n\t\tdata-input-name=\"wpforms_3723_11\"\n\t\tdata-extensions=\"jpg,jpeg,doc,xls,xlsx,odt,pptx,ppt,pdf,docx,odt,key\"\n\t\tdata-max-size=\"67108864\"\n\t\tdata-max-file-number=\"10\"\n\t\tdata-post-max-size=\"67108864\"\n\t\tdata-max-parallel-uploads=\"4\"\n\t\tdata-parallel-uploads=\"true\"\n\t\tdata-file-chunk-size=\"2097152\">\n\t<div class=\"dz-message\">\n\t\t<svg  viewBox=\"0 0 640 640\" focusable=\"false\" data-icon=\"inbox\" width=\"50px\" height=\"50px\" fill=\"currentColor\" aria-hidden=\"true\">\n\t\t\t<path d=\"M352 173.3L352 384C352 401.7 337.7 416 320 416C302.3 416 288 401.7 288 384L288 173.3L246.6 214.7C234.1 227.2 213.8 227.2 201.3 214.7C188.8 202.2 188.8 181.9 201.3 169.4L297.3 73.4C309.8 60.9 330.1 60.9 342.6 73.4L438.6 169.4C451.1 181.9 451.1 202.2 438.6 214.7C426.1 227.2 405.8 227.2 393.3 214.7L352 173.3zM320 464C364.2 464 400 428.2 400 384L480 384C515.3 384 544 412.7 544 448L544 480C544 515.3 515.3 544 480 544L160 544C124.7 544 96 515.3 96 480L96 448C96 412.7 124.7 384 160 384L240 384C240 428.2 275.8 464 320 464zM464 488C477.3 488 488 477.3 488 464C488 450.7 477.3 440 464 440C450.7 440 440 450.7 440 464C440 477.3 450.7 488 464 488z\"\/>\n\t\t<\/svg>\n\n\t\t<span class=\"modern-title\">\n\t\t\t\t\t\t\tDrag &amp; Drop Files, \t\t\t\t<span>Choose Files to Upload<\/span>\n\t\t\t\t\t<\/span>\n\n\t\t\t\t\t<span class=\"modern-hint\">You can upload up to 10 files.<\/span>\n\t\t\t<\/div>\n<\/div>\n\n<input\n\t\ttype=\"text\"\n\t\tautocomplete=\"off\"\n\t\treadonly\n\t\tclass=\"dropzone-input\"\n\t\tstyle=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\"\n\t\tid=\"wpforms-3723-field_11\"\n\t\tname=\"wpforms_3723_11\" \t\tvalue=\"\">\n<div class=\"wpforms-field-description\">Here you can upload photo material or other files. (max. 10 files of 10 mb each)<\/div><\/div><div id=\"wpforms-3723-field_9-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-3723-field_9\">Project description \/ requirements \/ your message to us:<\/label><textarea id=\"wpforms-3723-field_9\" class=\"wpforms-field-large\" name=\"wpforms[fields][9]\" ><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"3723\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/www.steinhoff.eu\/en\/wp-json\/wp\/v2\/pages\/3750\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-3723\" class=\"wpforms-submit\" data-alt-text=\"sending...\" data-submit-text=\"Send\" aria-live=\"assertive\" value=\"wpforms-submit\">Send<\/button><\/div><\/form><\/div>  <!-- .wpforms-container -->[\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row tm_bgimagefixed=&#8221;&#8221; css=&#8221;.vc_custom_1623671572496{padding-top: 88px !important;padding-bottom: 0px !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;2513&#8243; img_size=&#8221;full&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_custom_heading text=&#8221;Straightening &amp; Transport Rolls&#8221; font_container=&#8221;tag:h1|font_size:48px|text_align:left|color:%23014480|line_height:56px&#8221; google_fonts=&#8221;font_family:Poppins%3A100%2C100italic%2C200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C500%2C500italic%2C600%2C600italic%2C700%2C700italic%2C800%2C800italic%2C900%2C900italic|font_style:300%20light%20regular%3A300%3Anormal&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_custom_heading text=&#8221;YOUR INQUIRY&#8221; font_container=&#8221;tag:h1|font_size:48px|text_align:left|color:%23014480|line_height:56px&#8221; google_fonts=&#8221;font_family:Poppins%3A100%2C100italic%2C200%2C200italic%2C300%2C300italic%2Cregular%2Citalic%2C500%2C500italic%2C600%2C600italic%2C700%2C700italic%2C800%2C800italic%2C900%2C900italic|font_style:300%20light%20regular%3A300%3Anormal&#8221;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":5,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3750","page","type-page","status-publish","hentry"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.steinhoff.eu\/en\/wp-json\/wp\/v2\/pages\/3750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.steinhoff.eu\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.steinhoff.eu\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.steinhoff.eu\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.steinhoff.eu\/en\/wp-json\/wp\/v2\/comments?post=3750"}],"version-history":[{"count":4,"href":"https:\/\/www.steinhoff.eu\/en\/wp-json\/wp\/v2\/pages\/3750\/revisions"}],"predecessor-version":[{"id":3833,"href":"https:\/\/www.steinhoff.eu\/en\/wp-json\/wp\/v2\/pages\/3750\/revisions\/3833"}],"wp:attachment":[{"href":"https:\/\/www.steinhoff.eu\/en\/wp-json\/wp\/v2\/media?parent=3750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}